{"id":60628,"date":"2019-08-06T14:59:54","date_gmt":"2019-08-06T12:59:54","guid":{"rendered":"https:\/\/www.walraven.com\/en\/?page_id=55552"},"modified":"2024-09-11T10:49:22","modified_gmt":"2024-09-11T08:49:22","slug":"over-walraven","status":"publish","type":"page","link":"https:\/\/www.walraven.com\/be-nl\/over-walraven\/","title":{"rendered":"Over Walraven"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":43,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/tpl-landingspage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-60628","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Over Walraven - Walraven Belgi\u00eb<\/title>\n<meta name=\"description\" content=\"De Walraven Group heeft eigen productie- en verkoopkantoren in diverse landen en garandeert al 75 jaar lang de hoogste kwaliteit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.walraven.com\/be-nl\/over-walraven\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Over Walraven\" \/>\n<meta property=\"og:description\" content=\"De Walraven Group heeft eigen productie- en verkoopkantoren in diverse landen en garandeert al 75 jaar lang de hoogste kwaliteit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.walraven.com\/be-nl\/over-walraven\/\" \/>\n<meta property=\"og:site_name\" content=\"Walraven Belgi\u00eb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walravenbelgie\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T08:49:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/over-walraven\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/over-walraven\\\/\",\"name\":\"Over Walraven - Walraven Belgi\u00eb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/#website\"},\"datePublished\":\"2019-08-06T12:59:54+00:00\",\"dateModified\":\"2024-09-11T08:49:22+00:00\",\"description\":\"De Walraven Group heeft eigen productie- en verkoopkantoren in diverse landen en garandeert al 75 jaar lang de hoogste kwaliteit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/over-walraven\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/over-walraven\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/over-walraven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Over Walraven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/#website\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/\",\"name\":\"Walraven Belgi\u00eb\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/#organization\",\"name\":\"Walraven BV\",\"alternateName\":\"Walraven BV\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"width\":300,\"height\":300,\"caption\":\"Walraven BV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/be-nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walravenbelgie\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WalravenBENL\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walraven-belgi\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Over Walraven - Walraven Belgi\u00eb","description":"De Walraven Group heeft eigen productie- en verkoopkantoren in diverse landen en garandeert al 75 jaar lang de hoogste kwaliteit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.walraven.com\/be-nl\/over-walraven\/","og_locale":"nl_BE","og_type":"article","og_title":"Over Walraven","og_description":"De Walraven Group heeft eigen productie- en verkoopkantoren in diverse landen en garandeert al 75 jaar lang de hoogste kwaliteit.","og_url":"https:\/\/www.walraven.com\/be-nl\/over-walraven\/","og_site_name":"Walraven Belgi\u00eb","article_publisher":"https:\/\/www.facebook.com\/walravenbelgie","article_modified_time":"2024-09-11T08:49:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.walraven.com\/be-nl\/over-walraven\/","url":"https:\/\/www.walraven.com\/be-nl\/over-walraven\/","name":"Over Walraven - Walraven Belgi\u00eb","isPartOf":{"@id":"https:\/\/www.walraven.com\/be-nl\/#website"},"datePublished":"2019-08-06T12:59:54+00:00","dateModified":"2024-09-11T08:49:22+00:00","description":"De Walraven Group heeft eigen productie- en verkoopkantoren in diverse landen en garandeert al 75 jaar lang de hoogste kwaliteit.","breadcrumb":{"@id":"https:\/\/www.walraven.com\/be-nl\/over-walraven\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.walraven.com\/be-nl\/over-walraven\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.walraven.com\/be-nl\/over-walraven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.walraven.com\/be-nl\/"},{"@type":"ListItem","position":2,"name":"Over Walraven"}]},{"@type":"WebSite","@id":"https:\/\/www.walraven.com\/be-nl\/#website","url":"https:\/\/www.walraven.com\/be-nl\/","name":"Walraven Belgi\u00eb","description":"","publisher":{"@id":"https:\/\/www.walraven.com\/be-nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.walraven.com\/be-nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/www.walraven.com\/be-nl\/#organization","name":"Walraven BV","alternateName":"Walraven BV","url":"https:\/\/www.walraven.com\/be-nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/www.walraven.com\/be-nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.walraven.com\/be-nl\/wp-content\/uploads\/sites\/16\/2023\/12\/Walraven_logo300x300.jpg","contentUrl":"https:\/\/www.walraven.com\/be-nl\/wp-content\/uploads\/sites\/16\/2023\/12\/Walraven_logo300x300.jpg","width":300,"height":300,"caption":"Walraven BV"},"image":{"@id":"https:\/\/www.walraven.com\/be-nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walravenbelgie","https:\/\/www.youtube.com\/user\/WalravenBENL","https:\/\/www.linkedin.com\/company\/walraven-belgi\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/pages\/60628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/comments?post=60628"}],"version-history":[{"count":5,"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/pages\/60628\/revisions"}],"predecessor-version":[{"id":69518,"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/pages\/60628\/revisions\/69518"}],"wp:attachment":[{"href":"https:\/\/www.walraven.com\/be-nl\/wp-json\/wp\/v2\/media?parent=60628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}