{"id":90337,"date":"2024-04-17T09:53:51","date_gmt":"2024-04-17T07:53:51","guid":{"rendered":"https:\/\/www.walraven.com\/?page_id=135714"},"modified":"2026-02-03T07:35:58","modified_gmt":"2026-02-03T06:35:58","slug":"nachhaltigkeit","status":"publish","type":"page","link":"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/","title":{"rendered":"Nachhaltigkeit"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":43,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/tpl-landingspage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-90337","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nachhaltigkeit - Walraven Deutschland<\/title>\n<meta name=\"description\" content=\"Wir glauben fest daran, dass wir als multinationales Unternehmen mit Herz eine positive Wirkung im Bereich Nachhaltigkeit erzielen k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltigkeit\" \/>\n<meta property=\"og:description\" content=\"Wir glauben fest daran, dass wir als multinationales Unternehmen mit Herz eine positive Wirkung im Bereich Nachhaltigkeit erzielen k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Walraven Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Walraven.GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T06:35:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BIS_Tech\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/nachhaltigkeit\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/nachhaltigkeit\\\/\",\"name\":\"Nachhaltigkeit - Walraven Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#website\"},\"datePublished\":\"2024-04-17T07:53:51+00:00\",\"dateModified\":\"2026-02-03T06:35:58+00:00\",\"description\":\"Wir glauben fest daran, dass wir als multinationales Unternehmen mit Herz eine positive Wirkung im Bereich Nachhaltigkeit erzielen k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/nachhaltigkeit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.walraven.com\\\/de\\\/nachhaltigkeit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/nachhaltigkeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachhaltigkeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/\",\"name\":\"Walraven Deutschland\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#organization\",\"name\":\"Walraven GmbH\",\"alternateName\":\"Walraven GmbH\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"width\":300,\"height\":300,\"caption\":\"Walraven GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Walraven.GmbH\",\"https:\\\/\\\/x.com\\\/BIS_Tech\",\"https:\\\/\\\/www.youtube.com\\\/WalravenDE\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walraven-gmbh\",\"https:\\\/\\\/www.instagram.com\\\/walraven.gmbh\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nachhaltigkeit - Walraven Deutschland","description":"Wir glauben fest daran, dass wir als multinationales Unternehmen mit Herz eine positive Wirkung im Bereich Nachhaltigkeit erzielen k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/","og_locale":"de_DE","og_type":"article","og_title":"Nachhaltigkeit","og_description":"Wir glauben fest daran, dass wir als multinationales Unternehmen mit Herz eine positive Wirkung im Bereich Nachhaltigkeit erzielen k\u00f6nnen.","og_url":"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/","og_site_name":"Walraven Deutschland","article_publisher":"https:\/\/www.facebook.com\/Walraven.GmbH","article_modified_time":"2026-02-03T06:35:58+00:00","twitter_card":"summary_large_image","twitter_site":"@BIS_Tech","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/","url":"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/","name":"Nachhaltigkeit - Walraven Deutschland","isPartOf":{"@id":"https:\/\/www.walraven.com\/de\/#website"},"datePublished":"2024-04-17T07:53:51+00:00","dateModified":"2026-02-03T06:35:58+00:00","description":"Wir glauben fest daran, dass wir als multinationales Unternehmen mit Herz eine positive Wirkung im Bereich Nachhaltigkeit erzielen k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.walraven.com\/de\/nachhaltigkeit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.walraven.com\/de\/nachhaltigkeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.walraven.com\/de\/"},{"@type":"ListItem","position":2,"name":"Nachhaltigkeit"}]},{"@type":"WebSite","@id":"https:\/\/www.walraven.com\/de\/#website","url":"https:\/\/www.walraven.com\/de\/","name":"Walraven Deutschland","description":"","publisher":{"@id":"https:\/\/www.walraven.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.walraven.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.walraven.com\/de\/#organization","name":"Walraven GmbH","alternateName":"Walraven GmbH","url":"https:\/\/www.walraven.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.walraven.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2023\/12\/Walraven_logo300x300.jpg","contentUrl":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2023\/12\/Walraven_logo300x300.jpg","width":300,"height":300,"caption":"Walraven GmbH"},"image":{"@id":"https:\/\/www.walraven.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Walraven.GmbH","https:\/\/x.com\/BIS_Tech","https:\/\/www.youtube.com\/WalravenDE","https:\/\/www.linkedin.com\/company\/walraven-gmbh","https:\/\/www.instagram.com\/walraven.gmbh\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/pages\/90337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/comments?post=90337"}],"version-history":[{"count":7,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/pages\/90337\/revisions"}],"predecessor-version":[{"id":249007,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/pages\/90337\/revisions\/249007"}],"wp:attachment":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/media?parent=90337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}