{"id":234,"date":"2009-06-10T00:00:00","date_gmt":"2009-06-09T22:00:00","guid":{"rendered":"https:\/\/www.walraven.com\/de\/blog\/2016\/09\/29\/walraven-russland\/"},"modified":"2025-01-27T13:14:28","modified_gmt":"2025-01-27T12:14:28","slug":"walraven-russland","status":"publish","type":"post","link":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/","title":{"rendered":"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.walraven.com\/wp-content\/uploads\/sites\/4\/2014\/10\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg\" alt=\"Walraven in Russland\" \/>Walraven Group verst\u00e4rkt Aktivit\u00e4t in Russland<\/p>\n<p>Nach zwei Jahren jetzt mit eigenst\u00e4ndiger Vertriebsniederlassung<\/p>\n<p>Die russische Baubranche entwickelt sich rasant, qualitativ hochwertige Produkte sind immer mehr gefragt. So lauten die Erfahrungen der Mitarbeiter der Moskauer Verkaufsrepr\u00e4sentanz der international t\u00e4tigen Walraven Group nach zwei Jahren Engagement in Russland. Als Folge daraus gr\u00fcndete die Walraven Group mit Beginn des Jahres eine eigenst\u00e4ndige Vertriebsniederlassung in Moskau.<\/p>\n<p>Von Bayreuth aus erweiterte die Walraven Group 2009 die Aktivit\u00e4ten nach Russland. Als Teil der Walraven GmbH bauten zwei Mitarbeiter im Moskauer B\u00fcro Kontakte zu Gro\u00dfhandelskunden und Handwerksbetrieben auf, boten Schulungen, technische Beratung und Verkaufsf\u00f6rderma\u00dfnahmen an. In enger Zusammenarbeit mit den Partnern im Gro\u00dfhandel finden Walraven-Produkte immer h\u00e4ufiger den Weg in Installationsbetriebe und Bauprojekte. In den nur zwei Jahren baute das f\u00fcr Russland zust\u00e4ndige Team ein so weit reichendes Netz an Kontakten auf, dass die Walraven Group die 2009 gegr\u00fcndete Verkaufsrepr\u00e4sentanz mit Beginn des Jahres zu einer eigenst\u00e4ndigen Vertriebsniederlassung umwandelte. Verbunden mit einem Umzug in den Norden Moskaus.<\/p>\n<p>Wie bisher leitet der seit sechs Jahren bei Walraven t\u00e4tige Eduard Schunk, Jurist und Betriebswirt mit russischen Wurzeln, die Niederlassung in Moskau. Nun aber zus\u00e4tzlich unterst\u00fctzt von drei neuen Mitarbeitern. Ein verst\u00e4rktes Engagement, um die mit zwei Mitarbeitern begonnene Erfolgsgeschichte der Walraven Group in Russland fortzuschreiben.<\/p>\n<p>Die 1942 in Mijdrecht (Niederlande) gegr\u00fcndete Walraven Group ist ein international t\u00e4tiges Unternehmen mit 20 eigenen Produktions- und Verkaufsniederlassungen in Europa und den Vereinigten Staaten von Amerika. Die weltweit 700 Mitarbeiter des inhabergef\u00fchrten Unternehmens entwickeln, produzieren und vermarkten Befestigungs-, Brandschutz- und Sanit\u00e4rsysteme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Walraven Group verst\u00e4rkt Aktivit\u00e4t in Russland Nach zwei Jahren jetzt mit eigenst\u00e4ndiger Vertriebsniederlassung Die russische Baubranche entwickelt sich rasant, qualitativ hochwertige Produkte sind immer mehr gefragt. So lauten die Erfahrungen der Mitarbeiter der Moskauer Verkaufsrepr\u00e4sentanz der international t\u00e4tigen Walraven Group nach zwei Jahren Engagement in Russland. Als Folge daraus gr\u00fcndete die Walraven Group mit Beginn [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":4139,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[432],"tags":[],"class_list":["post-234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland<\/title>\n<meta name=\"description\" content=\"Die Walraven Group verst\u00e4rkt ihre Aktivit\u00e4t in Russland. Nach zwei Jahren jetzt mit einer eigenst\u00e4ndiger Vertriebsniederlassung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland\" \/>\n<meta property=\"og:description\" content=\"Die Walraven Group verst\u00e4rkt ihre Aktivit\u00e4t in Russland. Nach zwei Jahren jetzt mit einer eigenst\u00e4ndiger Vertriebsniederlassung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/\" \/>\n<meta property=\"og:site_name\" content=\"Walraven Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Walraven.GmbH\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-09T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T12:14:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2014\/10\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"139\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"clemens.dederl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BIS_Tech\" \/>\n<meta name=\"twitter:site\" content=\"@BIS_Tech\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"clemens.dederl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/\"},\"author\":{\"name\":\"clemens.dederl\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#\\\/schema\\\/person\\\/5aac3c4f1fbe0595c337615af839d821\"},\"headline\":\"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland\",\"datePublished\":\"2009-06-09T22:00:00+00:00\",\"dateModified\":\"2025-01-27T12:14:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/\"},\"wordCount\":281,\"publisher\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2014\\\/10\\\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/\",\"name\":\"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2014\\\/10\\\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg\",\"datePublished\":\"2009-06-09T22:00:00+00:00\",\"dateModified\":\"2025-01-27T12:14:28+00:00\",\"description\":\"Die Walraven Group verst\u00e4rkt ihre Aktivit\u00e4t in Russland. Nach zwei Jahren jetzt mit einer eigenst\u00e4ndiger Vertriebsniederlassung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2014\\\/10\\\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2014\\\/10\\\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg\",\"width\":200,\"height\":139},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/ueber-walraven\\\/aktuelles\\\/walraven-russland\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/\",\"name\":\"Walraven Deutschland\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#organization\",\"name\":\"Walraven GmbH\",\"alternateName\":\"Walraven GmbH\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"width\":300,\"height\":300,\"caption\":\"Walraven GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Walraven.GmbH\",\"https:\\\/\\\/x.com\\\/BIS_Tech\",\"https:\\\/\\\/www.youtube.com\\\/WalravenDE\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walraven-gmbh\",\"https:\\\/\\\/www.instagram.com\\\/walraven.gmbh\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/de\\\/#\\\/schema\\\/person\\\/5aac3c4f1fbe0595c337615af839d821\",\"name\":\"clemens.dederl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34ae201fd7991ed73d71ab76117c9370e60d8bb5349d31713df056b5a439d847?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34ae201fd7991ed73d71ab76117c9370e60d8bb5349d31713df056b5a439d847?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34ae201fd7991ed73d71ab76117c9370e60d8bb5349d31713df056b5a439d847?s=96&d=mm&r=g\",\"caption\":\"clemens.dederl\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland","description":"Die Walraven Group verst\u00e4rkt ihre Aktivit\u00e4t in Russland. Nach zwei Jahren jetzt mit einer eigenst\u00e4ndiger Vertriebsniederlassung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/","og_locale":"de_DE","og_type":"article","og_title":"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland","og_description":"Die Walraven Group verst\u00e4rkt ihre Aktivit\u00e4t in Russland. Nach zwei Jahren jetzt mit einer eigenst\u00e4ndiger Vertriebsniederlassung.","og_url":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/","og_site_name":"Walraven Deutschland","article_publisher":"https:\/\/www.facebook.com\/Walraven.GmbH","article_published_time":"2009-06-09T22:00:00+00:00","article_modified_time":"2025-01-27T12:14:28+00:00","og_image":[{"width":200,"height":139,"url":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2014\/10\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg","type":"image\/jpeg"}],"author":"clemens.dederl","twitter_card":"summary_large_image","twitter_creator":"@BIS_Tech","twitter_site":"@BIS_Tech","twitter_misc":{"Verfasst von":"clemens.dederl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/#article","isPartOf":{"@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/"},"author":{"name":"clemens.dederl","@id":"https:\/\/www.walraven.com\/de\/#\/schema\/person\/5aac3c4f1fbe0595c337615af839d821"},"headline":"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland","datePublished":"2009-06-09T22:00:00+00:00","dateModified":"2025-01-27T12:14:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/"},"wordCount":281,"publisher":{"@id":"https:\/\/www.walraven.com\/de\/#organization"},"image":{"@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/#primaryimage"},"thumbnailUrl":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2014\/10\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg","articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/","url":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/","name":"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland","isPartOf":{"@id":"https:\/\/www.walraven.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/#primaryimage"},"image":{"@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/#primaryimage"},"thumbnailUrl":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2014\/10\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg","datePublished":"2009-06-09T22:00:00+00:00","dateModified":"2025-01-27T12:14:28+00:00","description":"Die Walraven Group verst\u00e4rkt ihre Aktivit\u00e4t in Russland. Nach zwei Jahren jetzt mit einer eigenst\u00e4ndiger Vertriebsniederlassung.","breadcrumb":{"@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/#primaryimage","url":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2014\/10\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg","contentUrl":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2014\/10\/hzr4myjiq17ritv4hxndfg77lck6x59-5HheXA.jpg","width":200,"height":139},{"@type":"BreadcrumbList","@id":"https:\/\/www.walraven.com\/de\/ueber-walraven\/aktuelles\/walraven-russland\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.walraven.com\/de\/"},{"@type":"ListItem","position":2,"name":"Vertriebsniederlassung in Moskau f\u00fcr st\u00e4rkere Pr\u00e4senz in Russland"}]},{"@type":"WebSite","@id":"https:\/\/www.walraven.com\/de\/#website","url":"https:\/\/www.walraven.com\/de\/","name":"Walraven Deutschland","description":"","publisher":{"@id":"https:\/\/www.walraven.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.walraven.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.walraven.com\/de\/#organization","name":"Walraven GmbH","alternateName":"Walraven GmbH","url":"https:\/\/www.walraven.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.walraven.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2023\/12\/Walraven_logo300x300.jpg","contentUrl":"https:\/\/www.walraven.com\/de\/wp-content\/uploads\/sites\/4\/2023\/12\/Walraven_logo300x300.jpg","width":300,"height":300,"caption":"Walraven GmbH"},"image":{"@id":"https:\/\/www.walraven.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Walraven.GmbH","https:\/\/x.com\/BIS_Tech","https:\/\/www.youtube.com\/WalravenDE","https:\/\/www.linkedin.com\/company\/walraven-gmbh","https:\/\/www.instagram.com\/walraven.gmbh\/"]},{"@type":"Person","@id":"https:\/\/www.walraven.com\/de\/#\/schema\/person\/5aac3c4f1fbe0595c337615af839d821","name":"clemens.dederl","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/34ae201fd7991ed73d71ab76117c9370e60d8bb5349d31713df056b5a439d847?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34ae201fd7991ed73d71ab76117c9370e60d8bb5349d31713df056b5a439d847?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34ae201fd7991ed73d71ab76117c9370e60d8bb5349d31713df056b5a439d847?s=96&d=mm&r=g","caption":"clemens.dederl"}}]}},"_links":{"self":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/posts\/234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/comments?post=234"}],"version-history":[{"count":5,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/posts\/234\/revisions"}],"predecessor-version":[{"id":93233,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/posts\/234\/revisions\/93233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/media\/4139"}],"wp:attachment":[{"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/media?parent=234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/categories?post=234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.walraven.com\/de\/wp-json\/wp\/v2\/tags?post=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}