{"id":53638,"date":"2019-05-24T16:25:46","date_gmt":"2019-05-24T14:25:46","guid":{"rendered":"https:\/\/www.walraven.com\/en\/?page_id=54881"},"modified":"2025-07-14T10:51:16","modified_gmt":"2025-07-14T08:51:16","slug":"light-duty-clamps","status":"publish","type":"page","link":"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/","title":{"rendered":"Light Duty Clamps"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":43,"featured_media":0,"parent":53569,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/tpl-landingspage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-53638","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Light Duty Clamps - Walraven Norge<\/title>\n<meta name=\"description\" content=\"Walraven\u2019s Light Duty Clamps provide fast and reliable solutions to hold light load pipes. \u2705 Quick and easy installation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Light Duty Clamps\" \/>\n<meta property=\"og:description\" content=\"Walraven\u2019s Light Duty Clamps provide fast and reliable solutions to hold light load pipes. \u2705 Quick and easy installation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/\" \/>\n<meta property=\"og:site_name\" content=\"Walraven Norge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walravenINT\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T08:51:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/fixing-systems\\\/light-duty-clamps\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/fixing-systems\\\/light-duty-clamps\\\/\",\"name\":\"Light Duty Clamps - Walraven Norge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/#website\"},\"datePublished\":\"2019-05-24T14:25:46+00:00\",\"dateModified\":\"2025-07-14T08:51:16+00:00\",\"description\":\"Walraven\u2019s Light Duty Clamps provide fast and reliable solutions to hold light load pipes. \u2705 Quick and easy installation\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/fixing-systems\\\/light-duty-clamps\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.walraven.com\\\/no\\\/fixing-systems\\\/light-duty-clamps\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/fixing-systems\\\/light-duty-clamps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fixing Systems\",\"item\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/fixing-systems\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Light Duty Clamps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/\",\"name\":\"Walraven International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/#organization\",\"name\":\"Walraven International\",\"alternateName\":\"Walraven International B.V.\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2023\\\/12\\\/Walraven_logo300x300.jpg\",\"width\":300,\"height\":300,\"caption\":\"Walraven International\"},\"image\":{\"@id\":\"https:\\\/\\\/www.walraven.com\\\/no\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walravenINT\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/walravengroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walraven-group\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Light Duty Clamps - Walraven Norge","description":"Walraven\u2019s Light Duty Clamps provide fast and reliable solutions to hold light load pipes. \u2705 Quick and easy installation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/","og_locale":"nb_NO","og_type":"article","og_title":"Light Duty Clamps","og_description":"Walraven\u2019s Light Duty Clamps provide fast and reliable solutions to hold light load pipes. \u2705 Quick and easy installation","og_url":"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/","og_site_name":"Walraven Norge","article_publisher":"https:\/\/www.facebook.com\/walravenINT\/","article_modified_time":"2025-07-14T08:51:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/","url":"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/","name":"Light Duty Clamps - Walraven Norge","isPartOf":{"@id":"https:\/\/www.walraven.com\/no\/#website"},"datePublished":"2019-05-24T14:25:46+00:00","dateModified":"2025-07-14T08:51:16+00:00","description":"Walraven\u2019s Light Duty Clamps provide fast and reliable solutions to hold light load pipes. \u2705 Quick and easy installation","breadcrumb":{"@id":"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.walraven.com\/no\/fixing-systems\/light-duty-clamps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.walraven.com\/no\/"},{"@type":"ListItem","position":2,"name":"Fixing Systems","item":"https:\/\/www.walraven.com\/no\/fixing-systems\/"},{"@type":"ListItem","position":3,"name":"Light Duty Clamps"}]},{"@type":"WebSite","@id":"https:\/\/www.walraven.com\/no\/#website","url":"https:\/\/www.walraven.com\/no\/","name":"Walraven International","description":"","publisher":{"@id":"https:\/\/www.walraven.com\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.walraven.com\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/www.walraven.com\/no\/#organization","name":"Walraven International","alternateName":"Walraven International B.V.","url":"https:\/\/www.walraven.com\/no\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/www.walraven.com\/no\/#\/schema\/logo\/image\/","url":"https:\/\/www.walraven.com\/no\/wp-content\/uploads\/sites\/12\/2023\/12\/Walraven_logo300x300.jpg","contentUrl":"https:\/\/www.walraven.com\/no\/wp-content\/uploads\/sites\/12\/2023\/12\/Walraven_logo300x300.jpg","width":300,"height":300,"caption":"Walraven International"},"image":{"@id":"https:\/\/www.walraven.com\/no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walravenINT\/","https:\/\/www.youtube.com\/user\/walravengroup","https:\/\/www.linkedin.com\/company\/walraven-group\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/pages\/53638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/comments?post=53638"}],"version-history":[{"count":5,"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/pages\/53638\/revisions"}],"predecessor-version":[{"id":82768,"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/pages\/53638\/revisions\/82768"}],"up":[{"embeddable":true,"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/pages\/53569"}],"wp:attachment":[{"href":"https:\/\/www.walraven.com\/no\/wp-json\/wp\/v2\/media?parent=53638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}